{"id":1042,"date":"2017-08-21T14:29:46","date_gmt":"2017-08-21T11:29:46","guid":{"rendered":"http:\/\/corfudiary.com\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/"},"modified":"2017-08-22T15:32:24","modified_gmt":"2017-08-22T12:32:24","slug":"%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf","status":"publish","type":"post","link":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/","title":{"rendered":"Un bateau dans la mer Ionienne"},"content":{"rendered":"<p>Un beau dimanche du mois d\u2019ao\u00fbt, nous avons d\u00e9cid\u00e9 de faire du tourisme nous sur l\u2019\u00eele, et de prendre le bateau de Madalena et Corfou croisi\u00e8res et faire un tour autour du Nord de Corfou, combin\u00e9 avec BBQ.<br \/>\nNous avons commenc\u00e9 \u00e0 dix heures du port de gouvia et avec notre bateau piratique, nous avons commenc\u00e9 notre aventure. Premi\u00e8re escale ont \u00e9t\u00e9 les grottes de Saint Arsenios. Entre les plages de Agni et Krouzeri, sur des rochers intimidants, est construite la chapelle d\u2019Agios Arsenios. <img data-recalc-dims=\"1\" decoding=\"async\" class=\"lazyload  wp-image-1033 alignright\" src=\"https:\/\/i0.wp.com\/corfudiary.com\/wp-content\/uploads\/2017\/08\/%CF%83%CF%80%CE%B9%CE%BB%CE%B9%CE%B5%CF%827530641742567_1040672057_n.jpg?resize=199%2C265&#038;ssl=1\" data-orig-src=\"https:\/\/corfudiary.com\/wp-content\/uploads\/2017\/08\/\u03c3\u03c0\u03b9\u03bb\u03b9\u03b5\u03c27530641742567_1040672057_n-225x300.jpg\" alt=\"\" width=\"199\" height=\"265\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27199%27%20height%3D%27265%27%20viewBox%3D%270%200%20199%20265%27%3E%3Crect%20width%3D%27199%27%20height%3D%27265%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"\/wp-content\/uploads\/2017\/08\/\u03c3\u03c0\u03b9\u03bb\u03b9\u03b5\u03c27530641742567_1040672057_n.jpg 225w, \/wp-content\/uploads\/2017\/08\/\u03c3\u03c0\u03b9\u03bb\u03b9\u03b5\u03c27530641742567_1040672057_n.jpg 585w, \/wp-content\/uploads\/2017\/08\/\u03c3\u03c0\u03b9\u03bb\u03b9\u03b5\u03c27530641742567_1040672057_n.jpg 720w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/p>\n<p>Sous les pierres, il y a une grotte tr\u00e8s particuli\u00e8re.Sous les pierres, il y a une grotte extraordinaire. Nous sommes entr\u00e9s d\u2019un c\u00f4t\u00e9 et sorties de l\u2019autre passant sous le rocher avec une plong\u00e9e. Les eaux sont profondes mais impeccables ! Et ils ont une couleur vert-bleu, comme l\u2019\u00e9meraude.<br \/>\nLa prochain arr\u00eat \u00e9tait la plage de Limnopoyla. Juste un demi mile de Saint Saranda en Albanie, Limnopoyla Beach, mis \u00e0 part les eaux claires a une tr\u00e8s belle vue. Combinant une beaut\u00e9 sans pareil, comme en dehors de la for\u00eat, \u00e0 l\u2019arri\u00e8re de la plage, il est un lac, accessible aux visiteurs.  Bien s\u00fbr, mon excitation pour cette plage \u00e9tait double comme les capitaines ont commenc\u00e9 \u00e0 pr\u00e9parer le barbecue ! Barbecue sur la plage.<br \/>\nEt n\u2019oublions pas que nous \u00e9tions surtout pirates ! Et pirates sans se battre, ne sont pas des vrais pirates ! Tout le monde sait \u00e7a !  Sur la route, nous avons trouv\u00e9 un autre bateau de pirates et bien s\u00fbr on eu de d\u00e9vaster le navire rival ! Les enfants sont all\u00e9s \u00e0 l\u2019avant avec des pistolets \u00e0 eau et le capitaine attaquait les rivaux avec des seaux remplis d\u2019eau ! Qui a gagn\u00e9 et qui a perdu, inconnu. Peu il importait apr\u00e8s tout. Nous avons jou\u00e9 et l\u2019eau \u00e9tait rafra\u00eechissant et les enfants ont eu le temps de leur vie !<br \/>\nTremp\u00e9s, mais heureux, nous avons commenc\u00e9 \u00e0 rentrer. Nous avions un dernier arr\u00eat \u00e0 la plage de nissaki. C\u2019\u00e9tait la seule plage organis\u00e9e, avec tavernes et une caf\u00e9t\u00e9ria. Nous avons eu une heure pour d\u00e9couvrir cette plage, assez de temps pour boire un caf\u00e9 et profiter de la brise de mer. L\u2019eau avait encore une belle couleur d\u2019 \u00e9meraude et \u00e9tait impeccablement propre et agr\u00e9ablement frais !<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"lazyload  wp-image-1034 alignright\" src=\"https:\/\/i0.wp.com\/corfudiary.com\/wp-content\/uploads\/2017\/08\/21013726_10207530621622064_234651756_n.jpg?resize=264%2C198&#038;ssl=1\" data-orig-src=\"https:\/\/corfudiary.com\/wp-content\/uploads\/2017\/08\/21013726_10207530621622064_234651756_n-300x225.jpg\" alt=\"\" width=\"264\" height=\"198\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27264%27%20height%3D%27198%27%20viewBox%3D%270%200%20264%20198%27%3E%3Crect%20width%3D%27264%27%20height%3D%27198%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"\/wp-content\/uploads\/2017\/08\/21013726_10207530621622064_234651756_n.jpg 300w, \/wp-content\/uploads\/2017\/08\/21013726_10207530621622064_234651756_n.jpg 585w, \/wp-content\/uploads\/2017\/08\/21013726_10207530621622064_234651756_n.jpg 768w, \/wp-content\/uploads\/2017\/08\/21013726_10207530621622064_234651756_n.jpg 960w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 264px) 100vw, 264px\" \/><\/p>\n<p>Sur le chemin du retour, nous avons pass\u00e9 des colonies de Kouloura, Kalami et nous avons pass\u00e9 de Barbati, Dassia et Ipsos. Et comme nous \u00e9tions tous fatigu\u00e9s et nous \u00e9tions proches \u00e0 Gouvia, tout \u00e0 coup, les deux navires, Marilena et Maddalena ont \u00e9t\u00e9 rejoints, la musique classique de Zorba a commence a jouer et nos capitaine a saut\u00e9 afin de donner un r\u00e9cital de danse avec son fils et sa fille ! Nous l\u2019avons ador\u00e9 ! Imaginez comment les \u00e9trangers s\u2019est senti ! Et au moment o\u00f9 nous pensions que tout \u00e9tait finis, et ce qu\u2019un moment merveilleux, nous avons eu qui est fini. Le capitain de bord portait une perruque Afro noire, et avec son petit-fils sur ses \u00e9paules, il a commenc\u00e9 \u00e0 danser \u00e0 80 s airs, alors qu\u2019un membre de l\u2019\u00e9quipage portait une perruque avec des dreadlocks et se mit \u00e0 danser sur des rythmes reggae.<br \/>\nEt voil\u00e0 comment notre aventure a pris fin !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>  [&#8230;]<\/p>\n","protected":false},"author":10,"featured_media":1032,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[142,131,108],"tags":[323,154,238,169,111,140,358],"class_list":["post-1042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites","category-corfou","category-plages-de-corfou","tag-beaches-fr","tag-corfu-fr","tag-north-corfu-fr","tag-plages","tag-plages-en-corfou","tag-things-to-do-fr","tag-trip-around-corfu-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un bateau dans la mer Ionienne, une experience inoubliable | Corfu Diary<\/title>\n<meta name=\"description\" content=\"Un bateau dans la mer ionienne, une belle journ\u00e9e d&#039;ao\u00fbt, profitez de la brise de mer et le sel! Visiter Corfu Diary pour plus d&#039;informations!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corfudiary.com\/fr\/\u03ad\u03bd\u03b1-\u03ba\u03b1\u0390\u03ba\u03b9-\u03c3\u03c4\u03bf-\u03b9\u03cc\u03bd\u03b9\u03bf\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un bateau dans la mer Ionienne, une experience inoubliable | Corfu Diary\" \/>\n<meta property=\"og:description\" content=\"Un bateau dans la mer ionienne, une belle journ\u00e9e d&#039;ao\u00fbt, profitez de la brise de mer et le sel! Visiter Corfu Diary pour plus d&#039;informations!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corfudiary.com\/fr\/\u03ad\u03bd\u03b1-\u03ba\u03b1\u0390\u03ba\u03b9-\u03c3\u03c4\u03bf-\u03b9\u03cc\u03bd\u03b9\u03bf\/\" \/>\n<meta property=\"og:site_name\" content=\"Corfu Diary\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/corfudiary\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/themoulini\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-21T11:29:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-22T12:32:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corfudiary.com\/wp-content\/uploads\/2017\/08\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Themis Theodoropoulou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@corfudiary\" \/>\n<meta name=\"twitter:site\" content=\"@corfudiary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Themis Theodoropoulou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/\"},\"author\":{\"name\":\"Themis Theodoropoulou\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#\\\/schema\\\/person\\\/b0e959fe9961a3b48afa5e817d4abd5e\"},\"headline\":\"Un bateau dans la mer Ionienne\",\"datePublished\":\"2017-08-21T11:29:46+00:00\",\"dateModified\":\"2017-08-22T12:32:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/\"},\"wordCount\":566,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg\",\"keywords\":[\"beaches\",\"corfu\",\"North Corfu\",\"plages\",\"plages en Corfou\",\"things to do\",\"trip around corfu\"],\"articleSection\":[\"Activit\u00e9s\",\"Corfou\",\"Plages\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/\",\"url\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/\",\"name\":\"Un bateau dans la mer Ionienne, une experience inoubliable | Corfu Diary\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg\",\"datePublished\":\"2017-08-21T11:29:46+00:00\",\"dateModified\":\"2017-08-22T12:32:24+00:00\",\"description\":\"Un bateau dans la mer ionienne, une belle journ\u00e9e d'ao\u00fbt, profitez de la brise de mer et le sel! Visiter Corfu Diary pour plus d'informations!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#primaryimage\",\"url\":\"\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg\",\"width\":\"960\",\"height\":\"720\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un bateau dans la mer Ionienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#website\",\"url\":\"https:\\\/\\\/corfudiary.com\\\/\",\"name\":\"Corfu Diary\",\"description\":\"Your one-stop blog about Corfu Island\",\"publisher\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corfudiary.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#organization\",\"name\":\"CorfuDiary\",\"url\":\"https:\\\/\\\/corfudiary.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/corfudiary.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/main-logo.png?fit=450%2C100&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/corfudiary.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/main-logo.png?fit=450%2C100&ssl=1\",\"width\":450,\"height\":100,\"caption\":\"CorfuDiary\"},\"image\":{\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/corfudiary\\\/\",\"https:\\\/\\\/x.com\\\/corfudiary\",\"https:\\\/\\\/www.instagram.com\\\/corfudiary\\\/\",\"https:\\\/\\\/gr.pinterest.com\\\/corfudiary\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCykm5igZmtxxLinGmcFdtdg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/#\\\/schema\\\/person\\\/b0e959fe9961a3b48afa5e817d4abd5e\",\"name\":\"Themis Theodoropoulou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/corfudiary.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18bc648cbdea45c93676f571e44320ff.jpg?ver=1784077214\",\"url\":\"https:\\\/\\\/corfudiary.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18bc648cbdea45c93676f571e44320ff.jpg?ver=1784077214\",\"contentUrl\":\"https:\\\/\\\/corfudiary.com\\\/wp-content\\\/litespeed\\\/avatar\\\/18bc648cbdea45c93676f571e44320ff.jpg?ver=1784077214\",\"caption\":\"Themis Theodoropoulou\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themoulini\",\"them_them_\"],\"url\":\"https:\\\/\\\/corfudiary.com\\\/fr\\\/author\\\/themistheodoropoulou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un bateau dans la mer Ionienne, une experience inoubliable | Corfu Diary","description":"Un bateau dans la mer ionienne, une belle journ\u00e9e d'ao\u00fbt, profitez de la brise de mer et le sel! Visiter Corfu Diary pour plus d'informations!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corfudiary.com\/fr\/\u03ad\u03bd\u03b1-\u03ba\u03b1\u0390\u03ba\u03b9-\u03c3\u03c4\u03bf-\u03b9\u03cc\u03bd\u03b9\u03bf\/","og_locale":"fr_FR","og_type":"article","og_title":"Un bateau dans la mer Ionienne, une experience inoubliable | Corfu Diary","og_description":"Un bateau dans la mer ionienne, une belle journ\u00e9e d'ao\u00fbt, profitez de la brise de mer et le sel! Visiter Corfu Diary pour plus d'informations!","og_url":"https:\/\/corfudiary.com\/fr\/\u03ad\u03bd\u03b1-\u03ba\u03b1\u0390\u03ba\u03b9-\u03c3\u03c4\u03bf-\u03b9\u03cc\u03bd\u03b9\u03bf\/","og_site_name":"Corfu Diary","article_publisher":"https:\/\/www.facebook.com\/corfudiary\/","article_author":"https:\/\/www.facebook.com\/themoulini","article_published_time":"2017-08-21T11:29:46+00:00","article_modified_time":"2017-08-22T12:32:24+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/corfudiary.com\/wp-content\/uploads\/2017\/08\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg","type":"image\/jpeg"}],"author":"Themis Theodoropoulou","twitter_card":"summary_large_image","twitter_creator":"@corfudiary","twitter_site":"@corfudiary","twitter_misc":{"\u00c9crit par":"Themis Theodoropoulou","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#article","isPartOf":{"@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/"},"author":{"name":"Themis Theodoropoulou","@id":"https:\/\/corfudiary.com\/#\/schema\/person\/b0e959fe9961a3b48afa5e817d4abd5e"},"headline":"Un bateau dans la mer Ionienne","datePublished":"2017-08-21T11:29:46+00:00","dateModified":"2017-08-22T12:32:24+00:00","mainEntityOfPage":{"@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/"},"wordCount":566,"commentCount":0,"publisher":{"@id":"https:\/\/corfudiary.com\/#organization"},"image":{"@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2017\/08\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg","keywords":["beaches","corfu","North Corfu","plages","plages en Corfou","things to do","trip around corfu"],"articleSection":["Activit\u00e9s","Corfou","Plages"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/","url":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/","name":"Un bateau dans la mer Ionienne, une experience inoubliable | Corfu Diary","isPartOf":{"@id":"https:\/\/corfudiary.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#primaryimage"},"image":{"@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/2017\/08\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg","datePublished":"2017-08-21T11:29:46+00:00","dateModified":"2017-08-22T12:32:24+00:00","description":"Un bateau dans la mer ionienne, une belle journ\u00e9e d'ao\u00fbt, profitez de la brise de mer et le sel! Visiter Corfu Diary pour plus d'informations!","breadcrumb":{"@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#primaryimage","url":"\/wp-content\/uploads\/2017\/08\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg","contentUrl":"\/wp-content\/uploads\/2017\/08\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg","width":"960","height":"720"},{"@type":"BreadcrumbList","@id":"https:\/\/corfudiary.com\/fr\/%ce%ad%ce%bd%ce%b1-%ce%ba%ce%b1%ce%90%ce%ba%ce%b9-%cf%83%cf%84%ce%bf-%ce%b9%cf%8c%ce%bd%ce%b9%ce%bf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corfudiary.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Un bateau dans la mer Ionienne"}]},{"@type":"WebSite","@id":"https:\/\/corfudiary.com\/#website","url":"https:\/\/corfudiary.com\/","name":"Corfu Diary","description":"Your one-stop blog about Corfu Island","publisher":{"@id":"https:\/\/corfudiary.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corfudiary.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/corfudiary.com\/#organization","name":"CorfuDiary","url":"https:\/\/corfudiary.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/corfudiary.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/corfudiary.com\/wp-content\/uploads\/2021\/01\/main-logo.png?fit=450%2C100&ssl=1","contentUrl":"https:\/\/i0.wp.com\/corfudiary.com\/wp-content\/uploads\/2021\/01\/main-logo.png?fit=450%2C100&ssl=1","width":450,"height":100,"caption":"CorfuDiary"},"image":{"@id":"https:\/\/corfudiary.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/corfudiary\/","https:\/\/x.com\/corfudiary","https:\/\/www.instagram.com\/corfudiary\/","https:\/\/gr.pinterest.com\/corfudiary\/","https:\/\/www.youtube.com\/channel\/UCykm5igZmtxxLinGmcFdtdg"]},{"@type":"Person","@id":"https:\/\/corfudiary.com\/#\/schema\/person\/b0e959fe9961a3b48afa5e817d4abd5e","name":"Themis Theodoropoulou","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/corfudiary.com\/wp-content\/litespeed\/avatar\/18bc648cbdea45c93676f571e44320ff.jpg?ver=1784077214","url":"https:\/\/corfudiary.com\/wp-content\/litespeed\/avatar\/18bc648cbdea45c93676f571e44320ff.jpg?ver=1784077214","contentUrl":"https:\/\/corfudiary.com\/wp-content\/litespeed\/avatar\/18bc648cbdea45c93676f571e44320ff.jpg?ver=1784077214","caption":"Themis Theodoropoulou"},"sameAs":["https:\/\/www.facebook.com\/themoulini","them_them_"],"url":"https:\/\/corfudiary.com\/fr\/author\/themistheodoropoulou\/"}]}},"jetpack_featured_media_url":"\/wp-content\/uploads\/2017\/08\/\u03bc\u03b1\u03bd\u03c4\u03b1\u03bb\u03b5\u03bd\u03b16789661_n.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/posts\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":0,"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/posts\/1042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/media\/1032"}],"wp:attachment":[{"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/categories?post=1042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corfudiary.com\/fr\/wp-json\/wp\/v2\/tags?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}